{"id":1790,"count":6,"description":"","link":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/","name":"VES22E","slug":"ves22e","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VES22E Archive - Toengels Philips Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VES22E Archive - Toengels Philips Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/\" \/>\n<meta property=\"og:site_name\" content=\"Toengels Philips Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/toengel.net\/philipsblog\/wp-content\/uploads\/2019\/01\/Toengels-Philips-Blog-Logo_960x646px.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PhilipsToengel\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VES22E Archive - Toengels Philips Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/","og_locale":"de_DE","og_type":"article","og_title":"VES22E Archive - Toengels Philips Blog","og_url":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/","og_site_name":"Toengels Philips Blog","og_image":[{"width":960,"height":646,"url":"https:\/\/toengel.net\/philipsblog\/wp-content\/uploads\/2019\/01\/Toengels-Philips-Blog-Logo_960x646px.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@PhilipsToengel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/","url":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/","name":"VES22E Archive - Toengels Philips Blog","isPartOf":{"@id":"https:\/\/toengel.net\/philipsblog\/#website"},"breadcrumb":{"@id":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/toengel.net\/philipsblog\/tag\/ves22e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/toengel.net\/philipsblog\/"},{"@type":"ListItem","position":2,"name":"VES22E"}]},{"@type":"WebSite","@id":"https:\/\/toengel.net\/philipsblog\/#website","url":"https:\/\/toengel.net\/philipsblog\/","name":"Toengels Philips Blog","description":"Das (Support-) Forum \/ die Anlaufstelle f\u00fcr Philips Consumer Lifestyle (TV, Audio, Video, Multimedia, HUE, Sonicare und mehr)","publisher":{"@id":"https:\/\/toengel.net\/philipsblog\/#\/schema\/person\/61ade8f5b1d9e0c28a3d0340625c20aa"},"alternateName":"Das (Support-) Forum \/ die Anlaufstelle f\u00fcr Philips Consumer Lifestyle (TV, Audio, Video, Multimedia, HUE, Sonicare und mehr)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toengel.net\/philipsblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/toengel.net\/philipsblog\/#\/schema\/person\/61ade8f5b1d9e0c28a3d0340625c20aa","name":"Toengel","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/toengel.net\/philipsblog\/wp-content\/uploads\/2019\/01\/Toengels-Philips-Blog-Logo_512x512px.png","url":"https:\/\/toengel.net\/philipsblog\/wp-content\/uploads\/2019\/01\/Toengels-Philips-Blog-Logo_512x512px.png","contentUrl":"https:\/\/toengel.net\/philipsblog\/wp-content\/uploads\/2019\/01\/Toengels-Philips-Blog-Logo_512x512px.png","width":512,"height":512,"caption":"Toengel"},"logo":{"@id":"https:\/\/toengel.net\/philipsblog\/wp-content\/uploads\/2019\/01\/Toengels-Philips-Blog-Logo_512x512px.png"},"description":"Toengels Philips Blog gibt es seit Oktober 2010. Anf\u00e4nglich spezialisiert auf den Philips Cinema Platinum 21:9 (55PFL9955H\/12), fokussiert sich dieser Blog inzwischen auf viele Themen rund um Philips TV, Philips AVM (Audio, Video, Multimedia) und Philips Hue. Unterst\u00fctzen kannst du diesen Blog beim Einkauf \u00fcber Amazon oder via Spende f\u00fcr die Kaffeekasse.","sameAs":["https:\/\/toengel.net\/philipsblog\/","https:\/\/www.facebook.com\/PhilipsToengel\/","https:\/\/www.instagram.com\/philipstoengel\/","https:\/\/x.com\/PhilipsToengel","https:\/\/www.youtube.com\/c\/ToengelsPhilipsBlog"]}]}},"_links":{"self":[{"href":"https:\/\/toengel.net\/philipsblog\/wp-json\/wp\/v2\/tags\/1790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toengel.net\/philipsblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/toengel.net\/philipsblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/toengel.net\/philipsblog\/wp-json\/wp\/v2\/posts?tags=1790"},{"href":"https:\/\/toengel.net\/philipsblog\/wp-json\/wp\/v2\/pages?tags=1790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}